{"id":4267,"date":"2020-05-15T11:43:22","date_gmt":"2020-05-15T14:43:22","guid":{"rendered":"https:\/\/www.kadunew.com\/blog\/?p=4267"},"modified":"2020-05-15T11:43:22","modified_gmt":"2020-05-15T14:43:22","slug":"ferramenta-rejeitar-links-nao-mostra-propriedade","status":"publish","type":"post","link":"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade","title":{"rendered":"Ferramenta Rejeitar Links N\u00e3o Mostra a Propriedade"},"content":{"rendered":"<p>Uma d\u00favida muito comum. Usu\u00e1rios tentam rejeitar backlinks ruins, por\u00e9m ao acessar a <a href=\"https:\/\/www.google.com\/webmasters\/tools\/disavow-links-main?pli=1\" rel=\"noopener\" target=\"_blank\">Ferramenta Rejeitar Links<\/a> (Disavow links) n\u00e3o encontram a propriedade verificada no menu suspenso, a ferramenta mostra o campo em branco ou sem a propriedade desejada. Os sites s\u00e3o exibidos no painel do Search Console normalmente, por\u00e9m n\u00e3o s\u00e3o exibidos no menu suspenso Rejeitar Links, conforme imagem abaixo:<figure id=\"attachment_4269\" aria-describedby=\"caption-attachment-4269\" style=\"width: 666px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/rejeitar-links-n\u00e3o-aparece-propriedade.jpg\" alt=\"Propriedade n\u00e3o carrega\" width=\"666\" height=\"410\" class=\"size-full wp-image-4269\" srcset=\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/rejeitar-links-n\u00e3o-aparece-propriedade.jpg 666w, https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/rejeitar-links-n\u00e3o-aparece-propriedade-300x185.jpg 300w\" sizes=\"(max-width: 666px) 100vw, 666px\" \/><figcaption id=\"caption-attachment-4269\" class=\"wp-caption-text\">Ferramenta Rejeitar Links n\u00e3o lista propriedade<\/figcaption><\/figure><\/p>\n<h2>Solu\u00e7\u00e3o<\/h2>\n<p>A ferramenta de Rejeitar Links funciona apenas com <strong>propriedades de prefixo de URL<\/strong>. Portanto, para rejeitar os links voc\u00ea precisa verificar a propriedade por prefixo do URL (ver imagens abaixo).<\/p>\n<p>No canto superior esquerdo do <strong>Search Console<\/strong> clique na indica\u00e7\u00e3o da imagem abaixo e logo em seguida clique sobre &#8220;Adicionar propriedade&#8221;.<br \/>\n<figure id=\"attachment_4286\" aria-describedby=\"caption-attachment-4286\" style=\"width: 526px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/adicionar-propriedade.jpg\" alt=\"Adicionar Propriedade\" width=\"526\" height=\"213\" class=\"size-full wp-image-4286\" srcset=\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/adicionar-propriedade.jpg 526w, https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/adicionar-propriedade-300x121.jpg 300w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/><figcaption id=\"caption-attachment-4286\" class=\"wp-caption-text\">Adicionando nova propriedade<\/figcaption><\/figure><\/p>\n<p>Na sequ\u00eancia escolha a op\u00e7\u00e3o &#8220;Prefixo do URL&#8221;. Forne\u00e7a o dom\u00ednio do seu site <strong>exatamente como ele \u00e9 acessado<\/strong> (exemplo:com https, com ou sem www, etc).<br \/>\n<figure id=\"attachment_4271\" aria-describedby=\"caption-attachment-4271\" style=\"width: 757px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/verificacao-prefixo-de-url-1.jpg\" alt=\"Adicionando Prefixo de URL Search Console\" width=\"757\" height=\"546\" class=\"size-full wp-image-4271\" srcset=\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/verificacao-prefixo-de-url-1.jpg 757w, https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/verificacao-prefixo-de-url-1-300x216.jpg 300w\" sizes=\"(max-width: 757px) 100vw, 757px\" \/><figcaption id=\"caption-attachment-4271\" class=\"wp-caption-text\">Adicionando propriedade \u2013 Prefixo de URL<\/figcaption><\/figure><\/p>\n<div class=\"obs\">Mantenha as duas propriedades verificada (dom\u00ednio + prefixo do URL), n\u00e3o h\u00e1 problema algum. Use apenas a propriedade prefixo de URL para a ferramenta de Rejeitar Links.<\/div>\n<h2>Por que o problema acontece?<\/h2>\n<p>Quando voc\u00ea tem verificado uma propriedade de dom\u00ednio <strong>n\u00e3o \u00e9 poss\u00edvel usar a Ferramenta de Rejei\u00e7\u00e3o de Links<\/strong> (Disavow links). Essa ferramenta pertence ao <strong>Search Console antigo<\/strong>, quando n\u00e3o era poss\u00edvel a verifica\u00e7\u00e3o por dom\u00ednio.<\/p>\n<p>Para saber mais sobre verifica\u00e7\u00e3o de propriedade por <strong>dom\u00ednio ou prefixo de URL<\/strong> recomendo a leitura da documenta\u00e7\u00e3o <a href=\"https:\/\/support.google.com\/webmasters\/answer\/34592\" rel=\"noopener\" target=\"_blank\">Adicionar uma propriedade do site<\/a>.<\/p>\n<p>E para mais informa\u00e7\u00f5es sobre <strong>rejei\u00e7\u00e3o de links<\/strong> acesse a documenta\u00e7\u00e3o <a href=\"https:\/\/support.google.com\/webmasters\/answer\/2648487?hl=pt-BR\" rel=\"noopener\" target=\"_blank\">Rejeitar backlinks<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma d\u00favida muito comum. Usu\u00e1rios tentam rejeitar backlinks ruins, por\u00e9m ao acessar a Ferramenta Rejeitar Links (Disavow links) n\u00e3o encontram a propriedade verificada no menu suspenso, a ferramenta mostra o campo em branco ou sem a propriedade desejada. Os sites s\u00e3o exibidos no painel do Search Console normalmente, por\u00e9m n\u00e3o s\u00e3o exibidos no menu suspenso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-4267","post","type-post","status-publish","format-standard","hentry","category-seo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ferramenta Rejeitar Links N\u00e3o Mostra a Propriedade<\/title>\n<meta name=\"description\" content=\"Propriedade verificada n\u00e3o \u00e9 listada na Ferramenta Rejeitar Links? A ferramenta funciona apenas com propriedades Prefixo do URL. Saiba Mais!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferramenta Rejeitar Links N\u00e3o Mostra a Propriedade\" \/>\n<meta property=\"og:description\" content=\"Propriedade verificada n\u00e3o \u00e9 listada na Ferramenta Rejeitar Links? A ferramenta funciona apenas com propriedades Prefixo do URL. Saiba Mais!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade\" \/>\n<meta property=\"og:site_name\" content=\"KADUNEW\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-15T14:43:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/adicionar-propriedade.jpg\" \/>\n<meta name=\"author\" content=\"Kadu Oliveira\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kadu Oliveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade\",\"url\":\"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade\",\"name\":\"Ferramenta Rejeitar Links N\u00e3o Mostra a Propriedade\",\"isPartOf\":{\"@id\":\"https:\/\/www.kadunew.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/adicionar-propriedade.jpg\",\"datePublished\":\"2020-05-15T14:43:22+00:00\",\"dateModified\":\"2020-05-15T14:43:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.kadunew.com\/blog\/#\/schema\/person\/07b2297c4825efbd1e9f2a1018926b05\"},\"description\":\"Propriedade verificada n\u00e3o \u00e9 listada na Ferramenta Rejeitar Links? A ferramenta funciona apenas com propriedades Prefixo do URL. Saiba Mais!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade#primaryimage\",\"url\":\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/adicionar-propriedade.jpg\",\"contentUrl\":\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/adicionar-propriedade.jpg\",\"width\":526,\"height\":213,\"caption\":\"Adicionando nova propriedade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.kadunew.com\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEO\",\"item\":\"https:\/\/www.kadunew.com\/blog\/category\/seo\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ferramenta Rejeitar Links N\u00e3o Mostra a Propriedade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kadunew.com\/blog\/#website\",\"url\":\"https:\/\/www.kadunew.com\/blog\/\",\"name\":\"KADUNEW\",\"description\":\"Artigos sobre Front-End e Programa\u00e7\u00e3o web\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kadunew.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.kadunew.com\/blog\/#\/schema\/person\/07b2297c4825efbd1e9f2a1018926b05\",\"name\":\"Kadu Oliveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.kadunew.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/780660fded589936b30467c54c99d51a?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/780660fded589936b30467c54c99d51a?s=96&r=g\",\"caption\":\"Kadu Oliveira\"},\"sameAs\":[\"https:\/\/www.kadunew.com\/blog\"],\"url\":\"https:\/\/www.kadunew.com\/blog\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferramenta Rejeitar Links N\u00e3o Mostra a Propriedade","description":"Propriedade verificada n\u00e3o \u00e9 listada na Ferramenta Rejeitar Links? A ferramenta funciona apenas com propriedades Prefixo do URL. Saiba Mais!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade","og_locale":"pt_BR","og_type":"article","og_title":"Ferramenta Rejeitar Links N\u00e3o Mostra a Propriedade","og_description":"Propriedade verificada n\u00e3o \u00e9 listada na Ferramenta Rejeitar Links? A ferramenta funciona apenas com propriedades Prefixo do URL. Saiba Mais!","og_url":"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade","og_site_name":"KADUNEW","article_published_time":"2020-05-15T14:43:22+00:00","og_image":[{"url":"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/adicionar-propriedade.jpg"}],"author":"Kadu Oliveira","twitter_misc":{"Escrito por":"Kadu Oliveira","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade","url":"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade","name":"Ferramenta Rejeitar Links N\u00e3o Mostra a Propriedade","isPartOf":{"@id":"https:\/\/www.kadunew.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade#primaryimage"},"image":{"@id":"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade#primaryimage"},"thumbnailUrl":"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/adicionar-propriedade.jpg","datePublished":"2020-05-15T14:43:22+00:00","dateModified":"2020-05-15T14:43:22+00:00","author":{"@id":"https:\/\/www.kadunew.com\/blog\/#\/schema\/person\/07b2297c4825efbd1e9f2a1018926b05"},"description":"Propriedade verificada n\u00e3o \u00e9 listada na Ferramenta Rejeitar Links? A ferramenta funciona apenas com propriedades Prefixo do URL. Saiba Mais!","breadcrumb":{"@id":"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade#primaryimage","url":"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/adicionar-propriedade.jpg","contentUrl":"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2020\/05\/adicionar-propriedade.jpg","width":526,"height":213,"caption":"Adicionando nova propriedade"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kadunew.com\/blog\/seo\/ferramenta-rejeitar-links-nao-mostra-propriedade#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kadunew.com\/blog"},{"@type":"ListItem","position":2,"name":"SEO","item":"https:\/\/www.kadunew.com\/blog\/category\/seo"},{"@type":"ListItem","position":3,"name":"Ferramenta Rejeitar Links N\u00e3o Mostra a Propriedade"}]},{"@type":"WebSite","@id":"https:\/\/www.kadunew.com\/blog\/#website","url":"https:\/\/www.kadunew.com\/blog\/","name":"KADUNEW","description":"Artigos sobre Front-End e Programa\u00e7\u00e3o web","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kadunew.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.kadunew.com\/blog\/#\/schema\/person\/07b2297c4825efbd1e9f2a1018926b05","name":"Kadu Oliveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.kadunew.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/780660fded589936b30467c54c99d51a?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/780660fded589936b30467c54c99d51a?s=96&r=g","caption":"Kadu Oliveira"},"sameAs":["https:\/\/www.kadunew.com\/blog"],"url":"https:\/\/www.kadunew.com\/blog\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/posts\/4267"}],"collection":[{"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/comments?post=4267"}],"version-history":[{"count":20,"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/posts\/4267\/revisions"}],"predecessor-version":[{"id":4291,"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/posts\/4267\/revisions\/4291"}],"wp:attachment":[{"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/media?parent=4267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/categories?post=4267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/tags?post=4267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}