{"id":2683,"date":"2013-08-05T13:57:16","date_gmt":"2013-08-05T15:57:16","guid":{"rendered":"https:\/\/www.kadunew.com\/blog\/?p=2683"},"modified":"2015-05-14T19:02:24","modified_gmt":"2015-05-14T21:02:24","slug":"less-programando-no-css","status":"publish","type":"post","link":"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css","title":{"rendered":"LESS: Programando no CSS"},"content":{"rendered":"<figure style=\"width: 404px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2013\/08\/como-usar-less-css.png\" alt=\"Como usar LESS\" width=\"530\" height=\"200\" class=\"aligncenter size-full wp-image-2688\" \/><figcaption class=\"wp-caption-text\">Introdu\u00e7\u00e3o ao LESS<\/figcaption><\/figure>\n<p>Usando LESS para criar suas folhas de estilos \u00e9 poss\u00edvel deixar seu <strong>CSS muito mais din\u00e2mico<\/strong>. J\u00e1 imaginou usar vari\u00e1veis dentro da sua folha de estilos, ou melhor ainda, usar fun\u00e7\u00f5es iguais as que usamos quando estamos programando em PHP, JAVA, etc. A boa not\u00edcia \u00e9 que com a  ajuda de LESS n\u00f3s podemos.<br \/>\n<!--more Continuar lendo...--><br \/>\n<strong>LESS acrescenta funcionalidades din\u00e2micas para seu CSS<\/strong> e cada dia est\u00e1 sendo aprimorado e ficando mais r\u00e1pido; ele introduz a possibilidade de usar vari\u00e1veis, opera\u00e7\u00f5es e fun\u00e7\u00f5es na sua folha de estilo. Para quem j\u00e1 trabalha com CSS e tem uma no\u00e7\u00e3o b\u00e1sica de programa\u00e7\u00e3o se dar\u00e1 muito bem no aprendizado.<\/p>\n<h2>Usando LESS<\/h2>\n<p>Abaixo duas imagens que demostram o c\u00f3digo LESS e o CSS:<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2013\/08\/exemplos-less-um.png\" alt=\"Exemplo LESS\" width=\"516\" height=\"252\" class=\"aligncenter size-full wp-image-2684\" srcset=\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2013\/08\/exemplos-less-um.png 516w, https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2013\/08\/exemplos-less-um-300x146.png 300w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/><\/p>\n<figure style=\"width: 404px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2013\/08\/exemplos-less-dois.png\" alt=\"Exemplos LESS\" width=\"516\" height=\"220\" class=\"aligncenter size-full wp-image-2685\" \/><figcaption class=\"wp-caption-text\">Exemplo c\u00f3digo LESS e CSS<\/figcaption><\/figure>\n<h2>Como usar o LESS:<\/h2>\n<h3>Com JavaScript<\/h3>\n<p>Podemos usar um arquivo javascript onde a compila\u00e7\u00e3o vai ser feita de forma autom\u00e1tica. Basicamente esse arquivo interpreta as fun\u00e7\u00f5es, vari\u00e1veis do LESS e a cada carregamento da p\u00e1gina o arquivo JS faz a compila\u00e7\u00e3o do arquivo LESS.<\/p>\n<p>Fa\u00e7a o download do arquivo JavaScript no <a href=\"http:\/\/lesscss.org\/\">site oficial do LESS<\/a>.<\/p>\n<pre class=\"brush: xml; title: HTML; notranslate\" title=\"HTML\">\r\n&lt;link rel=&quot;stylesheet\/less&quot; type=&quot;text\/css&quot; href=&quot;style.less&quot;&gt;\r\n&lt;script src=&quot;less.js&quot; type=&quot;text\/javascript&quot;&gt;&lt;\/script&gt;\r\n<\/pre>\n<p>\u00c9 poss\u00edvel usar o link da biblioteca do Google para chamar o JavaScript:<\/p>\n<pre class=\"brush: xml; title: HTML; notranslate\" title=\"HTML\">\r\n&lt;script src=&quot;http:\/\/lesscss.googlecode.com\/files\/less-1.0.18.min.js&quot;&gt;&lt;\/script&gt; \r\n<\/pre>\n<div class=\"obs\">\nCertifique-se de linkar seu arquivo LESS antes do arquivo javascript. O navegador precisa baixar primeiro o arquivo feito em LESS para depois o JavaScript  reconhecer o LESS e fazer a convers\u00e3o. Perceba tamb\u00e9m que a extens\u00e3o da folha de estilos \u00e9 less e n\u00e3o css.\n<\/div>\n<h3>Compilar o arquivo LESS<\/h3>\n<p>A outra maneira \u00e9 fazer a compila\u00e7\u00e3o do arquivo LESS. Voc\u00ea monta todo o c\u00f3digo LESS e depois o converte para o tradicional CSS. <strong>Depois de convertido \u00e9 s\u00f3 copiar o que foi gerado pelo compilador e colar o c\u00f3digo na sua folha de estilos<\/strong>, simples n\u00e3o?<\/p>\n<p>Existem programas para fazer isso, e at\u00e9 online mesmo \u00e9 poss\u00edvel fazer. No <a href=\"http:\/\/winless.org\/\" title=\"Win less\">http:\/\/winless.org\/<\/a> voc\u00ea pode baixar o compilador ou converter o c\u00f3digo no pr\u00f3prio site. No site <a href=\"http:\/\/less2css.org\/\">less2css<\/a> tamb\u00e9m \u00e9 poss\u00edvel fazer essa convers\u00e3o.<\/p>\n<h2>LESS em a\u00e7\u00e3o<\/h2>\n<h3>Vari\u00e1veis<\/h3>\n<p>As vari\u00e1veis funcionam de forma semelhante como nas linguagens de programa\u00e7\u00e3o. <strong>Usamos as vari\u00e1veis para armazenar algum valor<\/strong>, logo usamos a vari\u00e1vel em vez de usarmos o valor em si.<\/p>\n<pre class=\"brush: css; title: CSS; notranslate\" title=\"CSS\">\r\n@header-font: Georgia;\r\nh1, h2, h3, h4 {\r\n    font-family: @header-font;\r\n}\r\n.large {\r\n    font-family:@header-font;\r\n}\r\n<\/pre>\n<p>No exemplo acima usamos uma vari\u00e1vel chamada <em>@header-font<\/em> (perceba a presen\u00e7a do &#8216;@&#8217; antes do nome da vari\u00e1vel) e atribu\u00edmos a ela o valor <em>Georgia<\/em>. A partir de agora podemos usar sempre essa vari\u00e1vel para atribuir a fonte <em>Georgia<\/em>. Abaixo um exemplo de uso de vari\u00e1veis com cores.<\/p>\n<pre class=\"brush: css; title: CSS; notranslate\" title=\"CSS\">\r\n@default-color: #4D926F;\r\n\r\n#header {\r\n  color: @default-color;\r\n}\r\n\r\nh2 {\r\n  color: @default-color;\r\n}\r\n<\/pre>\n<p><strong>Outro exemplo:<\/strong><\/p>\n<pre class=\"brush: css; title: CSS; notranslate\" title=\"CSS\">\r\n@color: #222222;\r\na {\r\n    @color: #ffffff;\r\n    color:@color;\r\n}\r\nbutton {\r\n    background: @color;\r\n}\r\n<\/pre>\n<p>No exemplo acima o LESS n\u00e3o ser\u00e1 convertido. Por qu\u00ea? Perceba que a vari\u00e1vel  @cor foi criada dentro de uma regra CSS, logo ela s\u00f3 ser\u00e1 vista dentro daquela regra. A vari\u00e1vel n\u00e3o \u00e9 acess\u00edvel fora deste escopo. Caso voc\u00ea defina uma vari\u00e1vel no inicio do seu arquivo LESS (fora das regras CSS) est\u00e1 fica dispon\u00edvel para qualquer regra CSS. <strong>Isso \u00e9 o conceito de escopo<\/strong>.<\/p>\n<h3>Opera\u00e7\u00f5es<\/h3>\n<p>Voc\u00ea pode definir um valor para uma vari\u00e1vel e usar  o valor dessa vari\u00e1vel para multiplicar, dividir, subtrair ou somar com outros valores, veja o exemplo abaixo:<\/p>\n<pre class=\"brush: css; title: CSS; notranslate\" title=\"CSS\">\r\n.button{\r\n    @unit: 3px;\r\n    border:@unit solid #ddd;\r\n    padding: @unit * 3;\r\n    margin: @unit * 2;\r\n}\r\n<\/pre>\n<p>Voc\u00ea pode usar esse conceito para alterar o valor de uma cor, veja:<\/p>\n<pre class=\"brush: css; title: CSS; notranslate\" title=\"CSS\">\r\n@color-button: #d24444;\r\ninput.submit {\r\n    color:#fff;\r\n    background:@color-button;\r\n    border:1px solid @color-button - #222;\r\n    padding:5px 12px;\r\n}\r\n<\/pre>\n<p>O C\u00f3digo acima cria um bot\u00e3o vermelho que tem uma borda um pouco mais escura. Isso ajuda pois n\u00e3o precisamos definir a cor da borda em separado. Caso queira mudar o bot\u00e3o para outra cor, \u00e9 s\u00f3 mudar a cor do bot\u00e3o que a\u00e7or da borda ser\u00e1 mudada de acordo com a cor do bot\u00e3o.<\/p>\n<p><strong>Outra vantagem \u00e9 no uso de gradientes, veja:<\/strong><\/p>\n<pre class=\"brush: css; title: CSS; notranslate\" title=\"CSS\">\r\n@color: #faa51a;\r\n.button {\r\n    background: -webkit-gradient(linear, left top, left bottom, from(@color + #151515), to(@color - #151515));\r\n    background: -moz-linear-gradient(top,  @color + #151515,  @color - #151515);\r\n}\r\n<\/pre>\n<h3>Aninhamento de regras<\/h3>\n<p>Veja como seria feito com CSS<\/p>\n<pre class=\"brush: css; title: CSS; notranslate\" title=\"CSS\">\r\n#header { color: black; }\r\n#header .navigation {\r\n  font-size: 12px;\r\n}\r\n#header .logo {\r\n  width: 300px;\r\n}\r\n#header .logo:hover {\r\n  text-decoration: none;\r\n}\r\n<\/pre>\n<p>Em LESS podemos fazer da seguinte forma (perceba que temos uma regra dentro de outra regra).<\/p>\n<pre class=\"brush: css; title: CSS; notranslate\" title=\"CSS\">\r\n#header {\r\n  color: black;\r\n\r\n  .navigation {\r\n    font-size: 12px;\r\n  }\r\n  .logo {\r\n    width: 300px;\r\n    &amp;amp;amp;amp;:hover { text-decoration: none }\r\n  }\r\n}\r\n<\/pre>\n<h3>Mixins<\/h3>\n<p><strong>Resumindo:<\/strong> Voc\u00ea pode usar uma declara\u00e7\u00e3o CSS dentro de outra. Veja o exemplo abaixo<\/p>\n<pre class=\"brush: css; title: CSS; notranslate\" title=\"CSS\">\r\n.rounded_top {\r\n    -webkit-border-top-left-radius: 6px;\r\n    -webkit-border-top-right-radius: 6px;\r\n    -moz-border-radius-topleft: 6px;\r\n    -moz-border-radius-topright: 6px;\r\n    border-top-left-radius: 6px;\r\n    border-top-right-radius: 6px;\r\n}\r\n.tab {\r\n    background: #000;\r\n    color:#fff;\r\n    .rounded_top;\r\n}\r\n.submit {\r\n    .tab;\r\n    background: red;\r\n}\r\n<\/pre>\n<p>No c\u00f3digo acima definimos uma classe <em>.rounded_top<\/em> que serve para arredondar os cantos na parte superior. Acrescentamos toda essa regra dentro da regra <strong>.tab<\/strong> (colocamos uma classe dentro de outra) A classe <em>.tab<\/em> al\u00e9m do fundo preto e letras brancas ter\u00e1 tamb\u00e9m os cantos arredondados na parte superior. E se n\u00e3o pastasse, dentro da regra <em>.submit<\/em> colocamos a regra <em>.tab<\/em>, que na verdade \u00e9 a classe <em>.tab<\/em> com uma jun\u00e7\u00e3o da classe <em>.rounded_top<\/em>. Fant\u00e1stico, n\u00e3o?!<\/p>\n<h3>Fun\u00e7\u00f5es em LESS<\/h3>\n<p>Se voc\u00ea j\u00e1 programou em qualquer linguagem de programa\u00e7\u00e3o est\u00e1 careca de saber o que \u00e9 uma fun\u00e7\u00e3o. Agora podemos usar esse conceito no CSS. Veja o exemplo abaixo e a seguir o coment\u00e1rio do c\u00f3digo.<\/p>\n<pre class=\"brush: css; title: CSS; notranslate\" title=\"CSS\">\r\n.rounded_top(@radius) {\r\n    -webkit-border-top-left-radius: @radius;\r\n    -webkit-border-top-right-radius: @radius;\r\n    -moz-border-radius-topleft: @radius;\r\n    -moz-border-radius-topright: @radius;\r\n    border-top-left-radius: @radius;\r\n    border-top-right-radius: @radius;\r\n}\r\n.tab {\r\n    background: #333;\r\n    color:#fff;\r\n    .rounded_top(6px);\r\n}\r\n.submit {\r\n    .rounded_top(3px);\r\n}\r\n<\/pre>\n<p>A regra <em>.rounded_top(@radius)<\/em> \u00e9 uma fun\u00e7\u00e3o, veja que nas regras abaixo chamamos as fun\u00e7\u00f5es passando os par\u00e2metros 6px e 3px.<\/p>\n<p>Podemos passar um par\u00e2metro padr\u00e3o para a fun\u00e7\u00e3o, veja:<\/p>\n<pre class=\"brush: css; title: CSS; notranslate\" title=\"CSS\">\r\n.rounded_top(@radius:6px) {\r\n    -webkit-border-top-left-radius: @radius;\r\n    -webkit-border-top-right-radius: @radius;\r\n    -moz-border-radius-topleft: @radius;\r\n    -moz-border-radius-topright: @radius;\r\n    border-top-left-radius: @radius;\r\n    border-top-right-radius: @radius;\r\n}\r\n.tab {\r\n    background: #333;\r\n    color:#fff;\r\n    .rounded_top;\r\n}\r\n.submit {\r\n    .rounded_top(3px);\r\n}\r\n<\/pre>\n<p>Na regra <em>.tab<\/em> ser\u00e1 acrescentado a regra <em>.rounded_top<\/em> como foi definida, ou seja, arredondamento de 6px j\u00e1 que n\u00e3o passamos par\u00e2metro algum. J\u00e1 na regra <em>.submit<\/em> o arredondamento foi alterado para 3px.<\/p>\n<h3>Namespaces<\/h3>\n<p><strong>Namespaces<\/strong> podem ser usados \u200b\u200bpara organizar o nosso CSS, permitindo-nos criar grupos de estilos. Como se fosse um encapsulamento das regras CSS.<\/p>\n<pre class=\"brush: css; title: CSS; notranslate\" title=\"CSS\">\r\n#defaults {\r\n\t.nav_list () {\r\n\t\tlist-style: none;\r\n\t\tmargin: 0; padding: 0;\r\n\t}\r\n\t.submit {\r\n        background: red;\r\n        color: white;\r\n        padding:5px 12px;\r\n    }\r\n\tp {\r\n        margin: 12px 0;\r\n    }\r\n}\r\n\r\n.submit_button {\r\n    #wrapper &gt; .submit;\r\n}\r\n<\/pre>\n<p>No exemplo acima temos um &#8220;pacote&#8221; chamado <em>#defaults<\/em>. Logo, aplicamos o estilo <em>.submit<\/em> a classe <em>.submit_button<\/em> que receber\u00e1 apenas a regra passada a ela.<\/p>\n<p><strong>LESS n\u00e3o \u00e9 a sua \u00fanica op\u00e7\u00e3o para um pr\u00e9-processador CSS<\/strong> . A outra op\u00e7\u00e3o popular \u00e9 <a href=\"http:\/\/sass-lang.com\/\">Sass<\/a>. A maior vantagem do LESS \u00e9 que ele usa uma sintaxe mais pr\u00f3xima do CSS.<\/p>\n<p>Para encerrar deixo um v\u00eddeo para voc\u00eas acompanharem alguns exemplos do LESS sendo usado. O v\u00eddeo est\u00e1 em ingl\u00eas mas s\u00f3 olhando j\u00e1 da para entender muita coisa.<\/p>\n<p><iframe loading=\"lazy\" width=\"540\" height=\"360\" src=\"\/\/www.youtube.com\/embed\/7OYPThQQPoc\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>Quer saber mais? segue alguns links de refer\u00eancia:<\/p>\n<ul>\n<li><a href=\"http:\/\/lesscss.org\/\">http:\/\/lesscss.org\/<\/a><\/li>\n<li><a href=\"http:\/\/webdesign.tutsplus.com\/tutorials\/htmlcss-tutorials\/get-into-less-the-programmable-stylesheet-language\/\">http:\/\/webdesign.tutsplus.com\/tutorials\/htmlcss-tutorials\/get-into-less-the-programmable-stylesheet-language\/<\/a><\/li>\n<li><a href=\"http:\/\/net.tutsplus.com\/tutorials\/html-css-techniques\/quick-tip-you-need-to-check-out-less-js\/\">http:\/\/net.tutsplus.com\/tutorials\/html-css-techniques\/quick-tip-you-need-to-check-out-less-js\/<\/a><\/li>\n<li><a href=\"http:\/\/coding.smashingmagazine.com\/2010\/12\/06\/using-the-less-css-preprocessor-for-smarter-style-sheets\/\">http:\/\/coding.smashingmagazine.com\/2010\/12\/06\/using-the-less-css-preprocessor-for-smarter-style-sheets\/<\/a><\/li>\n<\/ul>\n<p>Siga-me no Twitter: <a href=\"http:\/\/twitter.com\/kadunew\" rel=\"nofollow\">@kadunew<\/a> ou assine nosso <a href=\"https:\/\/www.kadunew.com\/blog\/feed\">Feed<\/a> e fique por dentro de todas atualiza\u00e7\u00f5es aqui do blog.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Usando LESS para criar suas folhas de estilos \u00e9 poss\u00edvel deixar seu CSS muito mais din\u00e2mico. J\u00e1 imaginou usar vari\u00e1veis dentro da sua folha de estilos, ou melhor ainda, usar fun\u00e7\u00f5es iguais as que usamos quando estamos programando em PHP, JAVA, etc. A boa not\u00edcia \u00e9 que com a ajuda de LESS n\u00f3s podemos.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2683","post","type-post","status-publish","format-standard","hentry","category-css"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LESS: Programando no CSS<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a o LESS que \u00e9 um pr\u00e9-processador de CSS e saiba como ele pode facilitar o seu trabalho. Veja exemplos e conceitos de como usar o LESS nos seus projetos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LESS: Programando no CSS\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a o LESS que \u00e9 um pr\u00e9-processador de CSS e saiba como ele pode facilitar o seu trabalho. Veja exemplos e conceitos de como usar o LESS nos seus projetos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css\" \/>\n<meta property=\"og:site_name\" content=\"KADUNEW\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-05T15:57:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-14T21:02:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2013\/08\/como-usar-less-css.png\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Kadu Oliveira\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kadu Oliveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css\",\"url\":\"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css\",\"name\":\"LESS: Programando no CSS\",\"isPartOf\":{\"@id\":\"https:\/\/www.kadunew.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2013\/08\/como-usar-less-css.png\",\"datePublished\":\"2013-08-05T15:57:16+00:00\",\"dateModified\":\"2015-05-14T21:02:24+00:00\",\"author\":{\"@id\":\"https:\/\/www.kadunew.com\/blog\/#\/schema\/person\/07b2297c4825efbd1e9f2a1018926b05\"},\"description\":\"Conhe\u00e7a o LESS que \u00e9 um pr\u00e9-processador de CSS e saiba como ele pode facilitar o seu trabalho. Veja exemplos e conceitos de como usar o LESS nos seus projetos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css#primaryimage\",\"url\":\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2013\/08\/como-usar-less-css.png\",\"contentUrl\":\"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2013\/08\/como-usar-less-css.png\",\"width\":540,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.kadunew.com\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CSS\",\"item\":\"https:\/\/www.kadunew.com\/blog\/category\/css\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LESS: Programando no CSS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kadunew.com\/blog\/#website\",\"url\":\"https:\/\/www.kadunew.com\/blog\/\",\"name\":\"KADUNEW\",\"description\":\"Artigos sobre Front-End e Programa\u00e7\u00e3o web\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kadunew.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.kadunew.com\/blog\/#\/schema\/person\/07b2297c4825efbd1e9f2a1018926b05\",\"name\":\"Kadu Oliveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.kadunew.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/780660fded589936b30467c54c99d51a?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/780660fded589936b30467c54c99d51a?s=96&r=g\",\"caption\":\"Kadu Oliveira\"},\"sameAs\":[\"https:\/\/www.kadunew.com\/blog\"],\"url\":\"https:\/\/www.kadunew.com\/blog\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LESS: Programando no CSS","description":"Conhe\u00e7a o LESS que \u00e9 um pr\u00e9-processador de CSS e saiba como ele pode facilitar o seu trabalho. Veja exemplos e conceitos de como usar o LESS nos seus projetos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css","og_locale":"pt_BR","og_type":"article","og_title":"LESS: Programando no CSS","og_description":"Conhe\u00e7a o LESS que \u00e9 um pr\u00e9-processador de CSS e saiba como ele pode facilitar o seu trabalho. Veja exemplos e conceitos de como usar o LESS nos seus projetos.","og_url":"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css","og_site_name":"KADUNEW","article_published_time":"2013-08-05T15:57:16+00:00","article_modified_time":"2015-05-14T21:02:24+00:00","og_image":[{"width":540,"height":200,"url":"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2013\/08\/como-usar-less-css.png","type":"image\/png"}],"author":"Kadu Oliveira","twitter_misc":{"Escrito por":"Kadu Oliveira","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css","url":"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css","name":"LESS: Programando no CSS","isPartOf":{"@id":"https:\/\/www.kadunew.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css#primaryimage"},"image":{"@id":"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css#primaryimage"},"thumbnailUrl":"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2013\/08\/como-usar-less-css.png","datePublished":"2013-08-05T15:57:16+00:00","dateModified":"2015-05-14T21:02:24+00:00","author":{"@id":"https:\/\/www.kadunew.com\/blog\/#\/schema\/person\/07b2297c4825efbd1e9f2a1018926b05"},"description":"Conhe\u00e7a o LESS que \u00e9 um pr\u00e9-processador de CSS e saiba como ele pode facilitar o seu trabalho. Veja exemplos e conceitos de como usar o LESS nos seus projetos.","breadcrumb":{"@id":"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css#primaryimage","url":"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2013\/08\/como-usar-less-css.png","contentUrl":"https:\/\/www.kadunew.com\/blog\/wp-content\/uploads\/2013\/08\/como-usar-less-css.png","width":540,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.kadunew.com\/blog\/css\/less-programando-no-css#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kadunew.com\/blog"},{"@type":"ListItem","position":2,"name":"CSS","item":"https:\/\/www.kadunew.com\/blog\/category\/css"},{"@type":"ListItem","position":3,"name":"LESS: Programando no CSS"}]},{"@type":"WebSite","@id":"https:\/\/www.kadunew.com\/blog\/#website","url":"https:\/\/www.kadunew.com\/blog\/","name":"KADUNEW","description":"Artigos sobre Front-End e Programa\u00e7\u00e3o web","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kadunew.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.kadunew.com\/blog\/#\/schema\/person\/07b2297c4825efbd1e9f2a1018926b05","name":"Kadu Oliveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.kadunew.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/780660fded589936b30467c54c99d51a?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/780660fded589936b30467c54c99d51a?s=96&r=g","caption":"Kadu Oliveira"},"sameAs":["https:\/\/www.kadunew.com\/blog"],"url":"https:\/\/www.kadunew.com\/blog\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/posts\/2683"}],"collection":[{"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/comments?post=2683"}],"version-history":[{"count":14,"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/posts\/2683\/revisions"}],"predecessor-version":[{"id":3978,"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/posts\/2683\/revisions\/3978"}],"wp:attachment":[{"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/media?parent=2683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/categories?post=2683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kadunew.com\/blog\/wp-json\/wp\/v2\/tags?post=2683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}